{"id":81,"date":"2017-03-22T19:17:25","date_gmt":"2017-03-22T19:17:25","guid":{"rendered":"http:\/\/nccororgms.wpengine.com\/tools-youthcompendium\/?page_id=81"},"modified":"2017-10-18T13:23:16","modified_gmt":"2017-10-18T13:23:16","slug":"view-by-individual-category","status":"publish","type":"page","link":"https:\/\/www.nccor.org\/tools-youthcompendium\/view-by-individual-category\/","title":{"rendered":"MET<sub>y<\/sub> Values (Observed\/Imputed) \u2013 View by Individual Category"},"content":{"rendered":"<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-active-play\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Active Play<\/a><\/h3>\n<div id=\"toggle-active-play\" class=\"toggle-content\">\n\n<table id=\"tablepress-8\" class=\"tablepress tablepress-id-8 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages<br\/>6-9<\/th><th class=\"column-4\">Ages<br\/>10-12<\/th><th class=\"column-5\">Ages<br\/>13-15<\/th><th class=\"column-6\">Ages<br\/>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">10100X<\/td><td class=\"column-2\">Ball Games - Bouncing, Kicking, Dribbling Ball, Reaction Ball (Moderate Intensity)<\/td><td class=\"column-3\"><b>6.1<\/b><\/td><td class=\"column-4\">5.4<\/td><td class=\"column-5\">6.6<\/td><td class=\"column-6\">6.6<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">10120X<\/td><td class=\"column-2\">Ball Games - Bouncing, Kicking, Dribbling Ball, Reaction Ball (Vigorous Intensity)<\/td><td class=\"column-3\"><b>6.3<\/b><\/td><td class=\"column-4\">6.2<\/td><td class=\"column-5\">6.9<\/td><td class=\"column-6\"><b>8.3<\/b><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">10140X<\/td><td class=\"column-2\">Dodgeball Type Games (E.G., Castles, Hot Feet)<\/td><td class=\"column-3\"><b>5.3<\/b><\/td><td class=\"column-4\">6.0<\/td><td class=\"column-5\">6.6<\/td><td class=\"column-6\">6.8<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">10160X<\/td><td class=\"column-2\">Free Play (Basketball, Rope, Hoop, Climb, Ladder, Frisbee)<\/td><td class=\"column-3\"><b>5.0<\/b><\/td><td class=\"column-4\"><b>5.8<\/b><\/td><td class=\"column-5\">5.8<\/td><td class=\"column-6\">5.9<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">10180X<\/td><td class=\"column-2\">Freeze\/Zone Tag (Moderate Intensity)<\/td><td class=\"column-3\"><b>5.5<\/b><\/td><td class=\"column-4\"><b>6.8<\/b><\/td><td class=\"column-5\">7.4<\/td><td class=\"column-6\">6.5<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">10200X<\/td><td class=\"column-2\">Freeze\/Zone Tag (Vigorous Intensity)<\/td><td class=\"column-3\">7.5<\/td><td class=\"column-4\"><b>6.7<\/b><\/td><td class=\"column-5\">6.3<\/td><td class=\"column-6\">6.2<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">10220X<\/td><td class=\"column-2\">Hiking<\/td><td class=\"column-3\">6.4<\/td><td class=\"column-4\">5.0<\/td><td class=\"column-5\">5.0<\/td><td class=\"column-6\"><b>5.9<\/b><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">10240X<\/td><td class=\"column-2\">Hopscotch<\/td><td class=\"column-3\"><b>5.8<\/b><\/td><td class=\"column-4\"><b>6.0<\/b><\/td><td class=\"column-5\">6.7<\/td><td class=\"column-6\">6.9<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">10260X<\/td><td class=\"column-2\">Jump Rope<\/td><td class=\"column-3\"><b>6.9<\/b><\/td><td class=\"column-4\"><b>6.0<\/b><\/td><td class=\"column-5\"><b>8.7<\/b><\/td><td class=\"column-6\"><b>8.7<\/b><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">10280X<\/td><td class=\"column-2\">Marching - 75M.Min Instruments<\/td><td class=\"column-3\">4.9<\/td><td class=\"column-4\">5.1<\/td><td class=\"column-5\"><b>5.2<\/b><\/td><td class=\"column-6\">6.3<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">10300X<\/td><td class=\"column-2\">Marching - 75M.Min No Instruments<\/td><td class=\"column-3\">3.8<\/td><td class=\"column-4\">4.0<\/td><td class=\"column-5\"><b>4.1<\/b><\/td><td class=\"column-6\">6.4<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">10320X<\/td><td class=\"column-2\">Marching - 91M.Min No Instruments<\/td><td class=\"column-3\">5.2<\/td><td class=\"column-4\">5.1<\/td><td class=\"column-5\"><b>5.3<\/b><\/td><td class=\"column-6\">5.8<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">10340X<\/td><td class=\"column-2\">Miscellaneous Games - Vigorous (E.G.,  Slap The Ball, Builders And Bulldozers, Clean The Room)<\/td><td class=\"column-3\"><b>7.2<\/b><\/td><td class=\"column-4\"><b>6.7<\/b><\/td><td class=\"column-5\">6.6<\/td><td class=\"column-6\">6.3<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">10360X<\/td><td class=\"column-2\">Miscellaneous Games - Moderate  (E.G.,  Simon'S Spotlight)<\/td><td class=\"column-3\">6.1<\/td><td class=\"column-4\"><b>6.2<\/b><\/td><td class=\"column-5\">6.3<\/td><td class=\"column-6\">6.5<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">10380X<\/td><td class=\"column-2\">Obstacle\/Locomotor Course - Moderate<\/td><td class=\"column-3\"><b>5.7<\/b><\/td><td class=\"column-4\"><b>5.8<\/b><\/td><td class=\"column-5\">5.5<\/td><td class=\"column-6\">7.8<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">10400X<\/td><td class=\"column-2\">Obstacle\/Locomotor Course - Vigorous<\/td><td class=\"column-3\"><b>7.2<\/b><\/td><td class=\"column-4\"><b>8.6<\/b><\/td><td class=\"column-5\">7.4<\/td><td class=\"column-6\">7.5<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">10420X<\/td><td class=\"column-2\">Playing Games (Catch And Throw Balls, Jumping Jacks)<\/td><td class=\"column-3\"><b>4.9<\/b><\/td><td class=\"column-4\"><b>5.1<\/b><\/td><td class=\"column-5\"><b>7.6<\/b><\/td><td class=\"column-6\"><b>5.9<\/b><\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">10440X<\/td><td class=\"column-2\">Playing Tag - Moderate<\/td><td class=\"column-3\"><b>5.9<\/b><\/td><td class=\"column-4\"><b>6.1<\/b><\/td><td class=\"column-5\">6.5<\/td><td class=\"column-6\">6.5<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">10460X<\/td><td class=\"column-2\">Playing Tag-Vigorous<\/td><td class=\"column-3\"><b>7.1<\/b><\/td><td class=\"column-4\"><b>8.3<\/b><\/td><td class=\"column-5\">8.1<\/td><td class=\"column-6\">8.3<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">10480X<\/td><td class=\"column-2\">Relay<\/td><td class=\"column-3\">6.5<\/td><td class=\"column-4\"><b>8.0<\/b><\/td><td class=\"column-5\">7.1<\/td><td class=\"column-6\">7.1<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">10500X<\/td><td class=\"column-2\">Sharks And Minnows<\/td><td class=\"column-3\"><b>5.2<\/b><\/td><td class=\"column-4\"><b>6.3<\/b><\/td><td class=\"column-5\">6.2<\/td><td class=\"column-6\">5.7<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">10520X<\/td><td class=\"column-2\">Trampoline<\/td><td class=\"column-3\">7.3<\/td><td class=\"column-4\"><b>8.2<\/b><\/td><td class=\"column-5\">7.1<\/td><td class=\"column-6\">7.6<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-8 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-active-video-games-full-body\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Active Video Games (Full Body)<\/a><\/h3>\n<div id=\"toggle-active-video-games-full-body\" class=\"toggle-content\">\n\n<table id=\"tablepress-9\" class=\"tablepress tablepress-id-9 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">15100X<\/td><td class=\"column-2\">Active Video Games - Action Running<\/td><td class=\"column-3\"><b>6.0<\/b><\/td><td class=\"column-4\">6.6<\/td><td class=\"column-5\">6.9<\/td><td class=\"column-6\">7.1<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">15120X<\/td><td class=\"column-2\">Active Video Games - Baseball<\/td><td class=\"column-3\">2.7<\/td><td class=\"column-4\"><b>5.8<\/b><\/td><td class=\"column-5\">6.2<\/td><td class=\"column-6\">6.7<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">15140X<\/td><td class=\"column-2\">Active Video Games - Boxing<\/td><td class=\"column-3\">2.7<\/td><td class=\"column-4\"><b>6.2<\/b><\/td><td class=\"column-5\"><b>4.4<\/b><\/td><td class=\"column-6\">5.1<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">15160X<\/td><td class=\"column-2\">Active Video Games - Catching Targets<\/td><td class=\"column-3\"><b>2.3<\/b><\/td><td class=\"column-4\"><b>5.4<\/b><\/td><td class=\"column-5\">4.8<\/td><td class=\"column-6\">5.7<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">15180X<\/td><td class=\"column-2\">Active Video Games - Dance<\/td><td class=\"column-3\"><b>3.0<\/b><\/td><td class=\"column-4\"><b>3.5<\/b><\/td><td class=\"column-5\"><b>3.7<\/b><\/td><td class=\"column-6\"><b>6.3<\/b><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">15200X<\/td><td class=\"column-2\">Active Video Games - Hoverboard<\/td><td class=\"column-3\">1.9<\/td><td class=\"column-4\"><b>2.8<\/b><\/td><td class=\"column-5\">3.5<\/td><td class=\"column-6\">4.3<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">15220X<\/td><td class=\"column-2\">Active Video Games - Kinect Adventure Games And Sports<\/td><td class=\"column-3\">3.6<\/td><td class=\"column-4\"><b>4.0<\/b><\/td><td class=\"column-5\">5.1<\/td><td class=\"column-6\">6.4<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">15240X<\/td><td class=\"column-2\">Active Video Games - Lightspace<\/td><td class=\"column-3\">2.8<\/td><td class=\"column-4\"><b>4.8<\/b><\/td><td class=\"column-5\">5.0<\/td><td class=\"column-6\">5.2<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">15260X<\/td><td class=\"column-2\">Active Video Games - Olympic Games<\/td><td class=\"column-3\"><b>2.5<\/b><\/td><td class=\"column-4\">3.5<\/td><td class=\"column-5\">4.4<\/td><td class=\"column-6\">6.1<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">15280X<\/td><td class=\"column-2\">Active Video Games - Sportwall<\/td><td class=\"column-3\">3.8<\/td><td class=\"column-4\"><b>5.2<\/b><\/td><td class=\"column-5\">5.4<\/td><td class=\"column-6\">6.7<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">15300X<\/td><td class=\"column-2\">Active Video Games - Trazer<\/td><td class=\"column-3\">2.4<\/td><td class=\"column-4\"><b>4.6<\/b><\/td><td class=\"column-5\">3.9<\/td><td class=\"column-6\">5.3<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">15320X<\/td><td class=\"column-2\">Active Video Games - Walking On Treadmill And Bowling<\/td><td class=\"column-3\"><b>2.6<\/b><\/td><td class=\"column-4\">3.7<\/td><td class=\"column-5\">5.2<\/td><td class=\"column-6\">6.5<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">15340X<\/td><td class=\"column-2\">Active Video Games - Watching Tv\/Dvd - Walking<\/td><td class=\"column-3\"><b>2.6<\/b><\/td><td class=\"column-4\">3.1<\/td><td class=\"column-5\">4.7<\/td><td class=\"column-6\">4.9<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">15360X<\/td><td class=\"column-2\">Active Video Games - Wii Aerobics<\/td><td class=\"column-3\">2.2<\/td><td class=\"column-4\">3.1<\/td><td class=\"column-5\"><b>4.5<\/b><\/td><td class=\"column-6\">5.0<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">15380X<\/td><td class=\"column-2\">Active Video Games - Wii Boxing\/Tennis<\/td><td class=\"column-3\"><b>2.3<\/b><\/td><td class=\"column-4\"><b>3.3<\/b><\/td><td class=\"column-5\"><b>3.6<\/b><\/td><td class=\"column-6\">4.9<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">15400X<\/td><td class=\"column-2\">Active Video Games - Wii Hockey<\/td><td class=\"column-3\">1.5<\/td><td class=\"column-4\"><b>1.7<\/b><\/td><td class=\"column-5\">3.0<\/td><td class=\"column-6\">4.0<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">15420X<\/td><td class=\"column-2\">Active Video Games - Wii Muscle Conditioning<\/td><td class=\"column-3\">1.5<\/td><td class=\"column-4\">1.8<\/td><td class=\"column-5\"><b>3.0<\/b><\/td><td class=\"column-6\">4.0<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">15440X<\/td><td class=\"column-2\">Active Video Games - Wii Skiing<\/td><td class=\"column-3\">1.6<\/td><td class=\"column-4\"><b>2.4<\/b><\/td><td class=\"column-5\">3.4<\/td><td class=\"column-6\">4.3<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">15460X<\/td><td class=\"column-2\">Active Video Games - Wii Step<\/td><td class=\"column-3\">2.3<\/td><td class=\"column-4\"><b>3.7<\/b><\/td><td class=\"column-5\">4.4<\/td><td class=\"column-6\">5.5<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">15480X<\/td><td class=\"column-2\">Active Video Games - Wii Tennis<\/td><td class=\"column-3\"><b>2.7<\/b><\/td><td class=\"column-4\"><b>2.4<\/b><\/td><td class=\"column-5\"><b>2.4<\/b><\/td><td class=\"column-6\">4.2<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">15500X<\/td><td class=\"column-2\">Active Video Games - Wii Yoga<\/td><td class=\"column-3\">1.9<\/td><td class=\"column-4\">1.9<\/td><td class=\"column-5\"><b>2.5<\/b><\/td><td class=\"column-6\">3.6<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">15520X<\/td><td class=\"column-2\">Active Video Games - Xavix<\/td><td class=\"column-3\">4.3<\/td><td class=\"column-4\"><b>6.3<\/b><\/td><td class=\"column-5\">6.2<\/td><td class=\"column-6\">6.8<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">15540X<\/td><td class=\"column-2\">Active Video Games (Compilation Of Games)<\/td><td class=\"column-3\"><b>4.5<\/b><\/td><td class=\"column-4\"><b>5.4<\/b><\/td><td class=\"column-5\"><b>6.0<\/b><\/td><td class=\"column-6\">5.9<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">15560X<\/td><td class=\"column-2\">Arcade Video Game - Air Hockey<\/td><td class=\"column-3\">2.2<\/td><td class=\"column-4\"><b>3.6<\/b><\/td><td class=\"column-5\">4.3<\/td><td class=\"column-6\">5.4<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">15580X<\/td><td class=\"column-2\">Arcade Video Game - Horse Riding Simulation<\/td><td class=\"column-3\">4.2<\/td><td class=\"column-4\"><b>6.4<\/b><\/td><td class=\"column-5\">5.9<\/td><td class=\"column-6\">6.9<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-9 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-active-video-games-upper-body\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Active Video Games (Upper Body)<\/a><\/h3>\n<div id=\"toggle-active-video-games-upper-body\" class=\"toggle-content\">\n\n<table id=\"tablepress-10\" class=\"tablepress tablepress-id-10 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">20100X<\/td><td class=\"column-2\">Active Video Games - Bowling<\/td><td class=\"column-3\"><b>1.8<\/b><\/td><td class=\"column-4\"><b>2.4<\/b><\/td><td class=\"column-5\"><b>2.4<\/b><\/td><td class=\"column-6\">2.7<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">20120X<\/td><td class=\"column-2\">Active Video Games - Driving Simulator<\/td><td class=\"column-3\">2.1<\/td><td class=\"column-4\"><b>2.0<\/b><\/td><td class=\"column-5\">2.5<\/td><td class=\"column-6\">2.1<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">20140X<\/td><td class=\"column-2\">Active Video Games - Wii (Compilation Of Games)<\/td><td class=\"column-3\"><b>2.5<\/b><\/td><td class=\"column-4\"><b>2.6<\/b><\/td><td class=\"column-5\"><b>2.8<\/b><\/td><td class=\"column-6\"><b>2.4<\/b><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">20160X<\/td><td class=\"column-2\">Active Video Games - Wii Balance<\/td><td class=\"column-3\">2.2<\/td><td class=\"column-4\">2.4<\/td><td class=\"column-5\"><b>2.4<\/b><\/td><td class=\"column-6\">2.8<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">20180X<\/td><td class=\"column-2\">Active Video Games - Wii Basketball<\/td><td class=\"column-3\">2.1<\/td><td class=\"column-4\"><b>2.3<\/b><\/td><td class=\"column-5\">2.4<\/td><td class=\"column-6\">2.5<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">20200X<\/td><td class=\"column-2\">Active Video Games - Wii Golf<\/td><td class=\"column-3\">2.1<\/td><td class=\"column-4\"><b>1.6<\/b><\/td><td class=\"column-5\">2.3<\/td><td class=\"column-6\">2.4<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">20220X<\/td><td class=\"column-2\">Arcade Video Game - Driving Simulation<\/td><td class=\"column-3\">2.0<\/td><td class=\"column-4\"><b>1.8<\/b><\/td><td class=\"column-5\">2.3<\/td><td class=\"column-6\">2.3<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">20240X<\/td><td class=\"column-2\">Arcade Video Game - Shooting Hoops<\/td><td class=\"column-3\">2.3<\/td><td class=\"column-4\"><b>3.2<\/b><\/td><td class=\"column-5\">2.7<\/td><td class=\"column-6\">2.7<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-10 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-bike-scooter\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Bike\/Scooter<\/a><\/h3>\n<div id=\"toggle-bike-scooter\" class=\"toggle-content\">\n\n<table id=\"tablepress-11\" class=\"tablepress tablepress-id-11 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">25100X<\/td><td class=\"column-2\">Riding A Bike - Fast Speed<\/td><td class=\"column-3\"><b>--<sup>a<\/sup><\/b><\/td><td class=\"column-4\"><b>7.1<\/b><\/td><td class=\"column-5\"><b>7.4<\/b><\/td><td class=\"column-6\"><b>7.8<\/b><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">25120X<\/td><td class=\"column-2\">Riding A Bike - Medium Speed<\/td><td class=\"column-3\"><b>4.5<\/b><\/td><td class=\"column-4\"><b>5.6<\/b><\/td><td class=\"column-5\"><b>5.8<\/b><\/td><td class=\"column-6\"><b>6.3<\/b><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">25140X<\/td><td class=\"column-2\">Riding A Bike - Self Paced<\/td><td class=\"column-3\">4.4<\/td><td class=\"column-4\"><b>5.4<\/b><\/td><td class=\"column-5\">5.3<\/td><td class=\"column-6\">7.0<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">25160X<\/td><td class=\"column-2\">Riding A Bike - Slow Speed<\/td><td class=\"column-3\"><b>3.6<\/b><\/td><td class=\"column-4\"><b>3.9<\/b><\/td><td class=\"column-5\"><b>3.9<\/b><\/td><td class=\"column-6\"><b>4.0<\/b><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">25180X<\/td><td class=\"column-2\">Riding A Mini - Scooter<\/td><td class=\"column-3\"><b>5.3<\/b><\/td><td class=\"column-4\">7.8<\/td><td class=\"column-5\">7.6<\/td><td class=\"column-6\">7.9<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">25200X<\/td><td class=\"column-2\">Riding Scooter<\/td><td class=\"column-3\"><b>5.0<\/b><\/td><td class=\"column-4\"><b>5.9<\/b><\/td><td class=\"column-5\">6.1<\/td><td class=\"column-6\">6.6<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-11 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-calisthenics-gymnastics\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Calisthenics\/Gymnastics<\/a><\/h3>\n<div id=\"toggle-calisthenics-gymnastics\" class=\"toggle-content\">\n\n<table id=\"tablepress-12\" class=\"tablepress tablepress-id-12 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">30100X<\/td><td class=\"column-2\">Active Classroom Instruction<\/td><td class=\"column-3\">4.3<\/td><td class=\"column-4\"><b>4.7<\/b><\/td><td class=\"column-5\">4.4<\/td><td class=\"column-6\">4.4<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">30120X<\/td><td class=\"column-2\">Broadcast Calisthenics - 'Colourful Sunshine'<\/td><td class=\"column-3\">4.1<\/td><td class=\"column-4\"><b>3.9<\/b><\/td><td class=\"column-5\">4.5<\/td><td class=\"column-6\">4.0<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">30140X<\/td><td class=\"column-2\">Broadcast Calisthenics - 'Flourishing Youth'<\/td><td class=\"column-3\">3.8<\/td><td class=\"column-4\">4.2<\/td><td class=\"column-5\">4.5<\/td><td class=\"column-6\"><b>4.3<\/b><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">30160X<\/td><td class=\"column-2\">Broadcast Calisthenics - 'Flying Ideal'<\/td><td class=\"column-3\">3.5<\/td><td class=\"column-4\">3.6<\/td><td class=\"column-5\"><b>3.8<\/b><\/td><td class=\"column-6\">3.6<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">30180X<\/td><td class=\"column-2\">Broadcast Calisthenics - 'Hopeful Sail'<\/td><td class=\"column-3\">3.7<\/td><td class=\"column-4\"><b>3.8<\/b><\/td><td class=\"column-5\">3.8<\/td><td class=\"column-6\">4.1<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">30200X<\/td><td class=\"column-2\">Calisthenics - Light<\/td><td class=\"column-3\"><b>3.8<\/b><\/td><td class=\"column-4\"><b>4.4<\/b><\/td><td class=\"column-5\">3.9<\/td><td class=\"column-6\">4.2<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">30220X<\/td><td class=\"column-2\">Gymnastics<\/td><td class=\"column-3\">2.7<\/td><td class=\"column-4\">2.9<\/td><td class=\"column-5\"><b>2.4<\/td><td class=\"column-6\">2.7<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">30240X<\/td><td class=\"column-2\">Jumping Jacks<\/td><td class=\"column-3\"><b>4.8<\/b><\/td><td class=\"column-4\">4.8<\/td><td class=\"column-5\">4.7<\/td><td class=\"column-6\">4.7<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">30260X<\/td><td class=\"column-2\">Radio Gymnastics<\/td><td class=\"column-3\">3.4<\/td><td class=\"column-4\"><b>3.4<\/b><\/td><td class=\"column-5\">3.6<\/td><td class=\"column-6\">3.6<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">30280X<\/td><td class=\"column-2\">Strength Exercises - Curl-Ups<\/td><td class=\"column-3\">2.3<\/td><td class=\"column-4\">2.3<\/td><td class=\"column-5\"><b>2.3<\/b><\/td><td class=\"column-6\"><b>2.3<\/b><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">30300X<\/td><td class=\"column-2\">Strength Exercises - Push-Ups<\/td><td class=\"column-3\">4.0<\/td><td class=\"column-4\">4.1<\/td><td class=\"column-5\"><b>4.2<\/b><\/td><td class=\"column-6\"><b>4.0<\/b><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-12 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-computer-video-games-sitting\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Computer\/Video Games (Sitting)<\/a><\/h3>\n<div id=\"toggle-computer-video-games-sitting\" class=\"toggle-content\">\n\n<table id=\"tablepress-13\" class=\"tablepress tablepress-id-13 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">35100X<\/td><td class=\"column-2\">Computer Games (Compilation Of Games)<\/td><td class=\"column-3\"><b>1.6<\/b><\/td><td class=\"column-4\"><b>1.5<\/b><\/td><td class=\"column-5\"><b>1.4<\/b><\/td><td class=\"column-6\"><b>1.3<\/b><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">35120X<\/td><td class=\"column-2\">Video Games - Bowling<\/td><td class=\"column-3\"><b>1.6<\/td><td class=\"column-4\">1.4<\/td><td class=\"column-5\">1.4<\/td><td class=\"column-6\">1.4<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">35140X<\/td><td class=\"column-2\">Video Games - Driving Simulator<\/td><td class=\"column-3\">1.3<\/td><td class=\"column-4\">1.4<\/td><td class=\"column-5\"><b>1.5<\/b><\/td><td class=\"column-6\">2.1<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">35160X<\/td><td class=\"column-2\">Video Games - Gameboy<\/td><td class=\"column-3\">1.3<\/td><td class=\"column-4\">1.5<\/td><td class=\"column-5\"><b>1.5<\/b><\/td><td class=\"column-6\">1.6<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">35180X<\/td><td class=\"column-2\">Video Games - Gamepad<\/td><td class=\"column-3\">1.3<\/td><td class=\"column-4\"><b>1.7<\/b><\/td><td class=\"column-5\">1.9<\/td><td class=\"column-6\">1.3<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">35200X<\/td><td class=\"column-2\">Video Games - Handheld<\/td><td class=\"column-3\"><b>1.9<\/b><\/td><td class=\"column-4\"><b>1.7<\/b><\/td><td class=\"column-5\">1.6<\/td><td class=\"column-6\">1.3<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">35220X<\/td><td class=\"column-2\">Video Games - Mobile Phone<\/td><td class=\"column-3\">1.6<\/td><td class=\"column-4\"><b>1.5<\/b><\/td><td class=\"column-5\">1.1<\/td><td class=\"column-6\">1.6<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">35240X<\/td><td class=\"column-2\">Video Games - Nintendo<\/td><td class=\"column-3\">1.4<\/td><td class=\"column-4\"><b>1.4<\/b><\/td><td class=\"column-5\">1.5<\/td><td class=\"column-6\">1.6<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">35260X<\/td><td class=\"column-2\">Video Games - Ps2<\/td><td class=\"column-3\"><b>1.2<\/b><\/td><td class=\"column-4\">1.6<\/td><td class=\"column-5\"><b>2.1<\/b><\/td><td class=\"column-6\">1.5<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">35280X<\/td><td class=\"column-2\">Video Games - Ps3<\/td><td class=\"column-3\">1.5<\/td><td class=\"column-4\"><b>1.5<\/b><\/td><td class=\"column-5\">1.5<\/td><td class=\"column-6\">1.5<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">35300X<\/td><td class=\"column-2\">Video Games - Xbox360<\/td><td class=\"column-3\">1.4<\/td><td class=\"column-4\"><b>1.5<\/b><\/td><td class=\"column-5\"><b>1.5<\/b><\/td><td class=\"column-6\">1.5<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">35320X<\/td><td class=\"column-2\">Video Games (Compilation Of Games)<\/td><td class=\"column-3\"><b>1.4<\/b><\/td><td class=\"column-4\"><b>1.6<\/b><\/td><td class=\"column-5\"><b>1.3<\/b><\/td><td class=\"column-6\"><b>1.4<\/b><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-13 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-dance-aerobics-steps\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i> Dance\/Aerobics\/Steps<\/a><\/h3>\n<div id=\"toggle-dance-aerobics-steps\" class=\"toggle-content\">\n\n<table id=\"tablepress-14\" class=\"tablepress tablepress-id-14 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">40100X<\/td><td class=\"column-2\">Aerobic Dance\/Dance<\/td><td class=\"column-3\"><b>3.6<\/b><\/td><td class=\"column-4\"><b>4.0<\/b><\/td><td class=\"column-5\"><b>4.8<\/b><\/td><td class=\"column-6\"><b>4.0<\/b><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">40120X<\/td><td class=\"column-2\">Stair Walking - Ascending<\/td><td class=\"column-3\"><b>4.6<\/b><\/td><td class=\"column-4\"><b>5.3<\/b><\/td><td class=\"column-5\"><b>5.9<\/b><\/td><td class=\"column-6\"><b>6.2<\/b><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">40140X<\/td><td class=\"column-2\">Stair Walking - Ascending 80 Steps\/Min<\/td><td class=\"column-3\">5.7<\/td><td class=\"column-4\">6.1<\/td><td class=\"column-5\"><b>7.0<\/b><\/td><td class=\"column-6\">6.9<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">40160X<\/td><td class=\"column-2\">Stair Walking - Ascending\/Descending<\/td><td class=\"column-3\"><b>5.7<\/b><\/td><td class=\"column-4\"><b>6.7<\/b><\/td><td class=\"column-5\"><b>7.6<\/b><\/td><td class=\"column-6\">7.4<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">40180X<\/td><td class=\"column-2\">Stair Walking - Descending<\/td><td class=\"column-3\">2.8<\/td><td class=\"column-4\">3.1<\/td><td class=\"column-5\"><b>3.2<\/b><\/td><td class=\"column-6\">4.2<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">40200X<\/td><td class=\"column-2\">Step Board<\/td><td class=\"column-3\">4.7<\/td><td class=\"column-4\"><b>5.7<\/b><\/td><td class=\"column-5\">5.7<\/td><td class=\"column-6\">6.1<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">40220X<\/td><td class=\"column-2\">Stepping - Height 30%-50% Leg Length<\/td><td class=\"column-3\">4.1<\/td><td class=\"column-4\"><b>4.1<\/b><\/td><td class=\"column-5\">4.7<\/td><td class=\"column-6\">5.5<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-14 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-housekeeping-work\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i> Housekeeping\/Work<\/a><\/h3>\n<div id=\"toggle-housekeeping-work\" class=\"toggle-content\">\n\n<table id=\"tablepress-15\" class=\"tablepress tablepress-id-15 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">45100X<\/td><td class=\"column-2\">Bedmaking<\/td><td class=\"column-3\">4.2<\/td><td class=\"column-4\"><b>3.2<\/b><\/td><td class=\"column-5\"><b>3.3<\/b><\/td><td class=\"column-6\">3.2<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">45120X<\/td><td class=\"column-2\">Carpentry<\/td><td class=\"column-3\"><b>2.3<\/b><\/td><td class=\"column-4\">2.6<\/td><td class=\"column-5\">2.2<\/td><td class=\"column-6\">1.8<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">45140X<\/td><td class=\"column-2\">Dressing And Undressing<\/td><td class=\"column-3\"><b>3.6<\/b><\/td><td class=\"column-4\"><b>3.0<\/b><\/td><td class=\"column-5\">3.2<\/td><td class=\"column-6\">2.6<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">45160X<\/td><td class=\"column-2\">Dusting<\/td><td class=\"column-3\">3.7<\/td><td class=\"column-4\"><b>3.4<\/b><\/td><td class=\"column-5\">3.2<\/td><td class=\"column-6\">2.3<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">45180X<\/td><td class=\"column-2\">Dusting And Sweeping<\/td><td class=\"column-3\"><b>3.6<\/b><\/td><td class=\"column-4\"><b>3.6<\/b><\/td><td class=\"column-5\"><b>2.4<\/b><\/td><td class=\"column-6\">2.9<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">45200X<\/td><td class=\"column-2\">Hanging Out Washing<\/td><td class=\"column-3\">3.2<\/td><td class=\"column-4\"><b>2.6<\/b><\/td><td class=\"column-5\">3.5<\/td><td class=\"column-6\">3.6<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">45220X<\/td><td class=\"column-2\">Housework<\/td><td class=\"column-3\"><b>4.0<\/b><\/td><td class=\"column-4\"><b>4.3<\/b><\/td><td class=\"column-5\"><b>4.4<\/b><\/td><td class=\"column-6\"><b>2.9<\/b><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">45240X<\/td><td class=\"column-2\">Laundry<\/td><td class=\"column-3\">4.2<\/td><td class=\"column-4\"><b>3.2<\/b><\/td><td class=\"column-5\">3.7<\/td><td class=\"column-6\">3.4<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">45260X<\/td><td class=\"column-2\">Loading\/Unloading Boxes<\/td><td class=\"column-3\"><b>3.5<\/td><td class=\"column-4\"><b>3.9<\/b><\/td><td class=\"column-5\">3.0<\/td><td class=\"column-6\">3.0<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">45280X<\/td><td class=\"column-2\">Setting The Table<\/td><td class=\"column-3\">2.7<\/td><td class=\"column-4\"><b>2.6<\/b><\/td><td class=\"column-5\">2.3<\/td><td class=\"column-6\">2.1<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">45300X<\/td><td class=\"column-2\">Shovelling<\/td><td class=\"column-3\"><b>3.9<\/b><\/td><td class=\"column-4\"><b>4.2<\/b><\/td><td class=\"column-5\"><b>4.3<\/b><\/td><td class=\"column-6\"><b>3.8<\/b><\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">45320X<\/td><td class=\"column-2\">Sweeping<\/td><td class=\"column-3\"><b>3.3<\/b><\/td><td class=\"column-4\"><b>3.6<\/b><\/td><td class=\"column-5\"><b>3.2<\/b><\/td><td class=\"column-6\"><b>3.1<\/b><\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">45340X<\/td><td class=\"column-2\">Vacuuming<\/td><td class=\"column-3\"><b>4.0<\/b><\/td><td class=\"column-4\"><b>3.7<\/b><\/td><td class=\"column-5\"><b>3.7<\/b><\/td><td class=\"column-6\"><b>3.7<\/b><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">45360X<\/td><td class=\"column-2\">Washing The Dishes<\/td><td class=\"column-3\"><b>1.9<\/b><\/td><td class=\"column-4\"><b>1.9<\/b><\/td><td class=\"column-5\"><b>2.0<\/b><\/td><td class=\"column-6\">2.4<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-15 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-lying\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Lying<\/a><\/h3>\n<div id=\"toggle-lying\" class=\"toggle-content\">\n\n<table id=\"tablepress-16\" class=\"tablepress tablepress-id-16 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">50100X<\/td><td class=\"column-2\">Quietly Lying<\/td><td class=\"column-3\"><b>1.3<\/b><\/td><td class=\"column-4\"><b>1.2<\/b><\/td><td class=\"column-5\"><b>1.1<\/b><\/td><td class=\"column-6\"><b>1.1<\/b><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">50120X<\/td><td class=\"column-2\">Watching TV\/DVD - Lying<\/td><td class=\"column-3\"><b>1.3<\/b><\/td><td class=\"column-4\"><b>1.0<\/b><\/td><td class=\"column-5\">1.1<\/td><td class=\"column-6\">1.1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-16 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-quiet-play-schoolwork-television-sitting\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Quiet Play\/Schoolwork\/Television (Sitting)<\/a><\/h3>\n<div id=\"toggle-quiet-play-schoolwork-television-sitting\" class=\"toggle-content\">\n\n<table id=\"tablepress-17\" class=\"tablepress tablepress-id-17 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">55100X<\/td><td class=\"column-2\">Arts And Crafts<\/td><td class=\"column-3\"><b>1.7<\/b><\/td><td class=\"column-4\"><b>1.6<\/b><\/td><td class=\"column-5\"><b>1.7<\/b><\/td><td class=\"column-6\">1.1<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">55120X<\/td><td class=\"column-2\">Board Games<\/td><td class=\"column-3\"><b>1.5<\/b><\/td><td class=\"column-4\"><b>1.5<\/td><td class=\"column-5\"><b>1.4<\/b><\/td><td class=\"column-6\"><b>1.5<\/b><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">55140X<\/td><td class=\"column-2\">Coloring, Reading Writing, Internet<\/td><td class=\"column-3\"><b>1.8<\/b><\/td><td class=\"column-4\"><b>1.5<\/td><td class=\"column-5\"><b>1.4<\/b><\/td><td class=\"column-6\"><b>1.4<\/b><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">55160X<\/td><td class=\"column-2\">Computer Work<\/td><td class=\"column-3\"><b>1.8<\/b><\/td><td class=\"column-4\"><b>1.4<\/b><\/td><td class=\"column-5\"><b>1.4<\/b><\/td><td class=\"column-6\">1.2<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">55180X<\/td><td class=\"column-2\">Giving A Speech<\/td><td class=\"column-3\">1.7<\/td><td class=\"column-4\">1.7<\/td><td class=\"column-5\"><b>1.1<\/b><\/td><td class=\"column-6\">1.6<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">55200X<\/td><td class=\"column-2\">Listening To Radio<\/td><td class=\"column-3\"><b>1.1<\/b><\/td><td class=\"column-4\"><b>1.3<\/b><\/td><td class=\"column-5\">1.5<\/td><td class=\"column-6\">1.4<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">55220X<\/td><td class=\"column-2\">Listening To Story<\/td><td class=\"column-3\"><b>1.1<\/b><\/td><td class=\"column-4\">1.4<\/td><td class=\"column-5\">1.4<\/td><td class=\"column-6\">1.3<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">55240X<\/td><td class=\"column-2\">Playing Quietly<\/td><td class=\"column-3\"><b>1.6<\/b><\/td><td class=\"column-4\"><b>1.6<\/b><\/td><td class=\"column-5\"><b>1.5<\/b><\/td><td class=\"column-6\">1.3<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">55260X<\/td><td class=\"column-2\">Playing Stringed Instrument<\/td><td class=\"column-3\">1.2<\/td><td class=\"column-4\">1.2<\/td><td class=\"column-5\"><b>1.6<\/b><\/td><td class=\"column-6\">1.1<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">55280X<\/td><td class=\"column-2\">Playing With Bricks<\/td><td class=\"column-3\"><b>1.3<\/td><td class=\"column-4\">1.1<\/td><td class=\"column-5\">1.0<\/td><td class=\"column-6\">1.0<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">55300X<\/td><td class=\"column-2\">Playing With Toys (Cards, Puzzles, Cars, Trains)<\/td><td class=\"column-3\">1.5<\/td><td class=\"column-4\"><b>1.4<\/b><\/td><td class=\"column-5\"><b>1.8<\/b><\/td><td class=\"column-6\">1.3<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">55320X<\/td><td class=\"column-2\">Puzzles<\/td><td class=\"column-3\">1.1<\/td><td class=\"column-4\"><b>1.3<\/b><\/td><td class=\"column-5\">1.1<\/td><td class=\"column-6\">1.0<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">55340X<\/td><td class=\"column-2\">Quietly Sitting<\/td><td class=\"column-3\"><b>1.4<\/b><\/td><td class=\"column-4\"><b>1.3<\/b><\/td><td class=\"column-5\"><b>1.3<\/b><\/td><td class=\"column-6\"><b>1.3<\/b><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">55360X<\/td><td class=\"column-2\">Reading<\/td><td class=\"column-3\"><b>1.5<\/b><\/td><td class=\"column-4\"><b>1.3<\/b><\/td><td class=\"column-5\"><b>1.0<\/b><\/td><td class=\"column-6\">1.1<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">55380X<\/td><td class=\"column-2\">Reading A Book And Listening To Music<\/td><td class=\"column-3\">1.6<\/td><td class=\"column-4\">1.1<\/td><td class=\"column-5\"><b>1.0<\/b><\/td><td class=\"column-6\">1.4<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">55400X<\/td><td class=\"column-2\">Schoolwork<\/td><td class=\"column-3\"><b>1.5<\/b><\/td><td class=\"column-4\"><b>1.8<\/b><\/td><td class=\"column-5\"><b>1.4<\/b><\/td><td class=\"column-6\">1.5<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">55420X<\/td><td class=\"column-2\">Sewing<\/td><td class=\"column-3\"><b>1.3<\/b><\/td><td class=\"column-4\"><b>1.6<\/b><\/td><td class=\"column-5\">1.5<\/td><td class=\"column-6\">1.4<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">55440X<\/td><td class=\"column-2\">Singing<\/td><td class=\"column-3\">1.2<\/td><td class=\"column-4\"><b>1.5<\/b><\/td><td class=\"column-5\">1.2<\/td><td class=\"column-6\">1.1<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">55460X<\/td><td class=\"column-2\">Talking With Friend<\/td><td class=\"column-3\"><b>1.0<\/b><\/td><td class=\"column-4\">1.6<\/td><td class=\"column-5\"><b>1.7<\/td><td class=\"column-6\">1.5<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">55480X<\/td><td class=\"column-2\">Watching Tv\/Dvd - Sitting<\/td><td class=\"column-3\"><b>1.3<\/b><\/td><td class=\"column-4\"><b>1.3<\/b><\/td><td class=\"column-5\"><b>1.2<\/b><\/td><td class=\"column-6\"><b>1.2<\/b><\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">55500X<\/td><td class=\"column-2\">Writing<\/td><td class=\"column-3\">1.5<\/td><td class=\"column-4\"><b>1.6<\/b><\/td><td class=\"column-5\"><b>1.2<\/b><\/td><td class=\"column-6\">1.3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-17 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-running\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Running<\/a><\/h3>\n<div id=\"toggle-running\" class=\"toggle-content\">\n\n<table id=\"tablepress-18\" class=\"tablepress tablepress-id-18 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">60100X<\/td><td class=\"column-2\">Jog - Fast<\/td><td class=\"column-3\"><b>7.0<\/b><\/td><td class=\"column-4\"><b>8.7<\/b><\/td><td class=\"column-5\">8.7<\/td><td class=\"column-6\">8.8<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">60120X<\/td><td class=\"column-2\">Jog - Slow<\/td><td class=\"column-3\"><b>5.6<\/b><\/td><td class=\"column-4\"><b>7.0<\/b><\/td><td class=\"column-5\">7.3<\/td><td class=\"column-6\">7.5<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">60140X<\/td><td class=\"column-2\">Jog Self-Paced<\/td><td class=\"column-3\">7.7<\/td><td class=\"column-4\"><b>7.5<\/b><\/td><td class=\"column-5\">7.6<\/td><td class=\"column-6\">8.0<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">60160X<\/td><td class=\"column-2\">Run 3.0<\/td><td class=\"column-3\"><b>5.3<\/b><\/td><td class=\"column-4\"><b>4.7<\/b><\/td><td class=\"column-5\"><b>--<sup>a<\/sup><\/b><\/td><td class=\"column-6\"><b>--<sup>a<\/sup><\/b><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">60180X<\/td><td class=\"column-2\">Run 3.5<\/td><td class=\"column-3\"><b>5.9<\/b><\/td><td class=\"column-4\"><b>6.9<\/b><\/td><td class=\"column-5\"><b>7.5<\/b><\/td><td class=\"column-6\"><b>8.3<\/b><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">60200X<\/td><td class=\"column-2\">Run 4.0<\/td><td class=\"column-3\"><b>6.5<\/b><\/td><td class=\"column-4\"><b>6.6<\/b><\/td><td class=\"column-5\"><b>7.4<\/b><\/td><td class=\"column-6\">8.2<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">60220X<\/td><td class=\"column-2\">Run 4.5<\/td><td class=\"column-3\"><b>6.8<\/b><\/td><td class=\"column-4\"><b>7.2<\/b><\/td><td class=\"column-5\"><b>8.5<\/b><\/td><td class=\"column-6\"><b>8.3<\/b><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">60240X<\/td><td class=\"column-2\">Run 5.0<\/td><td class=\"column-3\"><b>7.1<\/b><\/td><td class=\"column-4\"><b>8.1<\/b><\/td><td class=\"column-5\"><b>8.8<\/b><\/td><td class=\"column-6\"><b>9.0<\/b><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">60260X<\/td><td class=\"column-2\">Run 5.5<\/td><td class=\"column-3\"><b>7.2<\/b><\/td><td class=\"column-4\"><b>7.9<\/b><\/td><td class=\"column-5\"><b>9.2<\/b><\/td><td class=\"column-6\"><b>9.7<\/b><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">60280X<\/td><td class=\"column-2\">Run 6.0<\/td><td class=\"column-3\"><b>8.4<\/b><\/td><td class=\"column-4\"><b>8.8<\/b><\/td><td class=\"column-5\"><b>10.3<\/b><\/td><td class=\"column-6\"><b>10.6<\/b><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">60300X<\/td><td class=\"column-2\">Run 6.5<\/td><td class=\"column-3\"><b>8.1<\/b><\/td><td class=\"column-4\"><b>10.4<\/b><\/td><td class=\"column-5\"><b>11.7<\/b><\/td><td class=\"column-6\">11.9<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">60320X<\/td><td class=\"column-2\">Run 7.0<\/td><td class=\"column-3\">8.6<\/td><td class=\"column-4\"><b>10.7<\/b><\/td><td class=\"column-5\">11.2<\/td><td class=\"column-6\"><b>11.4<\/b><\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">60340X<\/td><td class=\"column-2\">Run 7.5<\/td><td class=\"column-3\"><b>10.6<\/b><\/td><td class=\"column-4\"><b>11.1<\/b><\/td><td class=\"column-5\"><b>12.4<\/b><\/td><td class=\"column-6\"><b>9.8<\/b><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">60360X<\/td><td class=\"column-2\">Run 8.0<\/td><td class=\"column-3\">10.9<\/td><td class=\"column-4\">11.6<\/td><td class=\"column-5\"><b>13.1<\/b><\/td><td class=\"column-6\"><b>12.7<\/b><\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">60380X<\/td><td class=\"column-2\">Run Self-Paced<\/td><td class=\"column-3\"><b>7.5<\/b><\/td><td class=\"column-4\"><b>8.8<\/b><\/td><td class=\"column-5\">9.1<\/td><td class=\"column-6\">9.5<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-18 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-sports-games\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Sports\/Games<\/a><\/h3>\n<div id=\"toggle-sports-games\" class=\"toggle-content\">\n\n<table id=\"tablepress-19\" class=\"tablepress tablepress-id-19 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">65100X<\/td><td class=\"column-2\">Basketball - Game<\/td><td class=\"column-3\"><b>6.2<\/b><\/td><td class=\"column-4\"><b>7.8<\/b><\/td><td class=\"column-5\"><b>7.3<\/b><\/td><td class=\"column-6\"><b>6.2<\/b><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">65120X<\/td><td class=\"column-2\">Basketball - Shooting And Retrieving A Basketball, Continuously, Without Stopping<\/td><td class=\"column-3\"><b>5.8<\/b><\/td><td class=\"column-4\"><b>5.9<\/b><\/td><td class=\"column-5\"><b>7.4<\/b><\/td><td class=\"column-6\">5.2<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">65140X<\/td><td class=\"column-2\">Basketball Game (Mini Basketball)<\/td><td class=\"column-3\">5.3<\/td><td class=\"column-4\"><b>4.4<\/b><\/td><td class=\"column-5\">5.3<\/td><td class=\"column-6\">4.7<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">65160X<\/td><td class=\"column-2\">Bowling - Game<\/td><td class=\"column-3\">4.3<\/td><td class=\"column-4\"><b>4.7<\/b><\/td><td class=\"column-5\">5.8<\/td><td class=\"column-6\">7.3<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">65180X<\/td><td class=\"column-2\">Boxing - Punching Bag And Gloves<\/td><td class=\"column-3\">5.2<\/td><td class=\"column-4\"><b>4.6<\/b><\/td><td class=\"column-5\">3.9<\/td><td class=\"column-6\">5.8<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">65200X<\/td><td class=\"column-2\">Catch\/Throw Ball<\/td><td class=\"column-3\"><b>3.5<\/b><\/td><td class=\"column-4\"><b>4.2<\/b><\/td><td class=\"column-5\">4.4<\/td><td class=\"column-6\">4.4<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">65220X<\/td><td class=\"column-2\">Golf - Game (Mini Golf)<\/td><td class=\"column-3\">4.1<\/td><td class=\"column-4\"><b>3.0<\/b><\/td><td class=\"column-5\">4.0<\/td><td class=\"column-6\">3.2<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">65240X<\/td><td class=\"column-2\">Handball<\/td><td class=\"column-3\">5.5<\/td><td class=\"column-4\"><b>5.4<\/b><\/td><td class=\"column-5\"><b>5.8<\/b><\/td><td class=\"column-6\">6.0<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">65260X<\/td><td class=\"column-2\">Hockey - Game (Mini Floor Hockey)<\/td><td class=\"column-3\">3.4<\/td><td class=\"column-4\"><b>4.0<\/b><\/td><td class=\"column-5\">3.1<\/td><td class=\"column-6\">2.7<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">65280X<\/td><td class=\"column-2\">Juggling<\/td><td class=\"column-3\">6.9<\/td><td class=\"column-4\"><b>5.4<\/b><\/td><td class=\"column-5\">7.9<\/td><td class=\"column-6\">6.6<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">65300X<\/td><td class=\"column-2\">Kickball, Continuous Movement<\/td><td class=\"column-3\">8.9<\/td><td class=\"column-4\"><b>8.4<\/b><\/td><td class=\"column-5\">8.8<\/td><td class=\"column-6\">8.7<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">65320X<\/td><td class=\"column-2\">Rollerblading<\/td><td class=\"column-3\">4.6<\/td><td class=\"column-4\"><b>6.9<\/b><\/td><td class=\"column-5\">5.4<\/td><td class=\"column-6\">4.1<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">65340X<\/td><td class=\"column-2\">Skiing<\/td><td class=\"column-3\">5.9<\/td><td class=\"column-4\">5.3<\/td><td class=\"column-5\"><b>6.5<\/b><\/td><td class=\"column-6\">6.3<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">65360X<\/td><td class=\"column-2\">Slide Board - 40 Slides\/Min<\/td><td class=\"column-3\">4.9<\/td><td class=\"column-4\"><b>5.0<\/b><\/td><td class=\"column-5\">4.6<\/td><td class=\"column-6\">4.9<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">65380X<\/td><td class=\"column-2\">Slide Board - 50 Slides\/Min<\/td><td class=\"column-3\">5.6<\/td><td class=\"column-4\"><b>5.5<\/b><\/td><td class=\"column-5\">5.8<\/td><td class=\"column-6\">5.6<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">65400X<\/td><td class=\"column-2\">Slide Board - 60 Slides\/Min<\/td><td class=\"column-3\">5.5<\/td><td class=\"column-4\"><b>5.9<\/b><\/td><td class=\"column-5\">5.9<\/td><td class=\"column-6\">6.4<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">65420X<\/td><td class=\"column-2\">Slide Board - 70 Slides\/Min<\/td><td class=\"column-3\">6.1<\/td><td class=\"column-4\"><b>6.5<\/b><\/td><td class=\"column-5\">6.5<\/td><td class=\"column-6\">6.6<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">65440X<\/td><td class=\"column-2\">Slide Board - 80 Slides\/Min<\/td><td class=\"column-3\">7.2<\/td><td class=\"column-4\"><b>7.4<\/b><\/td><td class=\"column-5\">7.6<\/td><td class=\"column-6\">7.8<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">65460X<\/td><td class=\"column-2\">Soccer - Around Cones<\/td><td class=\"column-3\"><b>5.6<\/b><\/td><td class=\"column-4\"><b>5.1<\/b><\/td><td class=\"column-5\"><b>6.1<\/b><\/td><td class=\"column-6\">6.1<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">65480X<\/td><td class=\"column-2\">Soccer - Game<\/td><td class=\"column-3\"><b>8.5<\/b><\/td><td class=\"column-4\"><b>8.5<\/b><\/td><td class=\"column-5\"><b>9.0<\/b><\/td><td class=\"column-6\">8.3<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">65500X<\/td><td class=\"column-2\">Table Tennis<\/td><td class=\"column-3\">3.9<\/td><td class=\"column-4\">4.0<\/td><td class=\"column-5\"><b>2.9<\/b><\/td><td class=\"column-6\">4.6<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">65520X<\/td><td class=\"column-2\">Tennis Practice And Games<\/td><td class=\"column-3\"><b>6.6<\/b><\/td><td class=\"column-4\"><b>5.9<\/b><\/td><td class=\"column-5\"><b>7.0<\/b><\/td><td class=\"column-6\"><b>6.7<\/b><\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">65540X<\/td><td class=\"column-2\">Ultimate Frisbbe<\/td><td class=\"column-3\">5.3<\/td><td class=\"column-4\"><b>6.1<\/b><\/td><td class=\"column-5\">5.7<\/td><td class=\"column-6\">6.6<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">65560X<\/td><td class=\"column-2\">Volleyball<\/td><td class=\"column-3\">5.0<\/td><td class=\"column-4\"><b>4.4<\/b><\/td><td class=\"column-5\">5.0<\/td><td class=\"column-6\">5.8<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-19 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-standing\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Standing<\/a><\/h3>\n<div id=\"toggle-standing\" class=\"toggle-content\">\n\n<table id=\"tablepress-20\" class=\"tablepress tablepress-id-20 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub>  Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">70100X<\/td><td class=\"column-2\">Arcade Games - Table Football<\/td><td class=\"column-3\">1.8<\/td><td class=\"column-4\">1.8<\/td><td class=\"column-5\"><b>1.8<\/b><\/td><td class=\"column-6\">1.7<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">70120X<\/td><td class=\"column-2\">Board Games - Standing<\/td><td class=\"column-3\">2.4<\/td><td class=\"column-4\"><b>2.2<\/b><\/td><td class=\"column-5\">1.4<\/td><td class=\"column-6\">2.3<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">70140X<\/td><td class=\"column-2\">Drawing, Coloring - Standing<\/td><td class=\"column-3\">1.6<\/td><td class=\"column-4\"><b>2.0<\/b><\/td><td class=\"column-5\">2.0<\/td><td class=\"column-6\">2.0<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">70160X<\/td><td class=\"column-2\">Singing - Standing<\/td><td class=\"column-3\"><b>1.3<\/b><\/td><td class=\"column-4\"><b>1.6<\/b><\/td><td class=\"column-5\">2.3<\/td><td class=\"column-6\">1.5<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">70180X<\/td><td class=\"column-2\">Stacking Cups<\/td><td class=\"column-3\"><b>2.3<\/b><\/td><td class=\"column-4\"><b>2.4<\/b><\/td><td class=\"column-5\"><b>1.4<\/b><\/td><td class=\"column-6\"><b>1.5<\/b><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">70200X<\/td><td class=\"column-2\">Standing<\/td><td class=\"column-3\">1.7<\/td><td class=\"column-4\">1.6<\/td><td class=\"column-5\"><b>1.6<\/td><td class=\"column-6\">1.2<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">70220X<\/td><td class=\"column-2\">Video Games - Standing<\/td><td class=\"column-3\"><b>1.7<\/b><\/td><td class=\"column-4\"><b>1.7<\/b><\/td><td class=\"column-5\"><b>1.6<\/b><\/td><td class=\"column-6\"><b>1.6<\/b><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">70240X<\/td><td class=\"column-2\">Watching Tv\/Dvd - Standing<\/td><td class=\"column-3\">1.7<\/td><td class=\"column-4\"><b>1.5<\/b><\/td><td class=\"column-5\">1.8<\/td><td class=\"column-6\">1.8<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-20 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-swimming\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Swimming<\/a><\/h3>\n<div id=\"toggle-swimming\" class=\"toggle-content\">\n\n<table id=\"tablepress-21\" class=\"tablepress tablepress-id-21 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">75100X<\/td><td class=\"column-2\">Swimming - 200M<\/td><td class=\"column-3\">11.3<\/td><td class=\"column-4\"><b>10.5<\/b><\/td><td class=\"column-5\">11.0<\/td><td class=\"column-6\">10.1<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">75120X<\/td><td class=\"column-2\">Swimming - Front Crawl 0.9 M.Sec<\/td><td class=\"column-3\">7.9<\/td><td class=\"column-4\"><b>8.3<\/b><\/td><td class=\"column-5\">8.5<\/td><td class=\"column-6\">8.8<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">75140X<\/td><td class=\"column-2\">Swimming - Front Crawl 1.0 M.Sec<\/td><td class=\"column-3\">9.9<\/td><td class=\"column-4\"><b>9.6<\/b><\/td><td class=\"column-5\">8.5<\/td><td class=\"column-6\">9.8<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">75160X<\/td><td class=\"column-2\">Swimming - Front Crawl 1.1 M.Sec<\/td><td class=\"column-3\">10.7<\/td><td class=\"column-4\"><b>11.4<\/b><\/td><td class=\"column-5\">10.1<\/td><td class=\"column-6\">10.2<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">75180X<\/td><td class=\"column-2\">Swimming - Self-Selected Pace<\/td><td class=\"column-3\"><b>7.0<\/b><\/td><td class=\"column-4\"><b>8.5<\/b><\/td><td class=\"column-5\"><b>9.5<\/b><\/td><td class=\"column-6\"><b>9.3<\/b><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">75200X<\/td><td class=\"column-2\">Synchronised Swimming<\/td><td class=\"column-3\">10.5<\/td><td class=\"column-4\">9.5<\/td><td class=\"column-5\"><b>10.1<\/b><\/td><td class=\"column-6\">9.8<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-21 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-walking\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Walking<\/a><\/h3>\n<div id=\"toggle-walking\" class=\"toggle-content\">\n\n<table id=\"tablepress-22\" class=\"tablepress tablepress-id-22 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">80100X<\/td><td class=\"column-2\">Walk 0.5<\/td><td class=\"column-3\"><b>2.5<\/b><\/td><td class=\"column-4\"><b>2.5<\/b><\/td><td class=\"column-5\"><b>2.3<\/b><\/td><td class=\"column-6\"><b>2.4<\/b><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">80120X<\/td><td class=\"column-2\">Walk 1.0<\/td><td class=\"column-3\"><b>2.8<\/b><\/td><td class=\"column-4\"><b>2.8<\/b><\/td><td class=\"column-5\"><b>2.7<\/b><\/td><td class=\"column-6\"><b>2.7<\/b><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">80140X<\/td><td class=\"column-2\">Walk 1.5<\/td><td class=\"column-3\"><b>2.3<\/b><\/td><td class=\"column-4\"><b>2.7<\/b><\/td><td class=\"column-5\"><b>3.0<\/b><\/td><td class=\"column-6\"><b>3.2<\/b><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">80160X<\/td><td class=\"column-2\">Walk 2.0<\/td><td class=\"column-3\"><b>2.7<\/b><\/td><td class=\"column-4\"><b>3.1<\/b><\/td><td class=\"column-5\"><b>3.1<\/b><\/td><td class=\"column-6\"><b>3.3<\/b><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">80180X<\/td><td class=\"column-2\">Walk 2.5<\/td><td class=\"column-3\"><b>3.2<\/b><\/td><td class=\"column-4\"><b>3.7<\/b><\/td><td class=\"column-5\"><b>3.4<\/b><\/td><td class=\"column-6\"><b>3.6<\/b><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">80200X<\/td><td class=\"column-2\">Walk 3.0<\/td><td class=\"column-3\"><b>3.7<\/b><\/td><td class=\"column-4\"><b>4.4<\/b><\/td><td class=\"column-5\"><b>4.0<\/b><\/td><td class=\"column-6\"><b>4.7<\/b><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">80220X<\/td><td class=\"column-2\">Walk 3.5<\/td><td class=\"column-3\"><b>4.6<\/b><\/td><td class=\"column-4\"><b>5.1<\/b><\/td><td class=\"column-5\"><b>5.1<\/b><\/td><td class=\"column-6\"><b>5.6<\/b><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">80240X<\/td><td class=\"column-2\">Walk 4.0<\/td><td class=\"column-3\"><b>4.9<\/b><\/td><td class=\"column-4\"><b>5.3<\/b><\/td><td class=\"column-5\"><b>5.3<\/b><\/td><td class=\"column-6\"><b>6.2<\/b><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">80260X<\/td><td class=\"column-2\">Walk 4.5<\/td><td class=\"column-3\"><b>--<sup>a<\/sup><\/b><\/td><td class=\"column-4\"><b>--<sup>a<\/sup><\/b><\/td><td class=\"column-5\"><b>6.4<\/b><\/td><td class=\"column-6\"><b>8.1<\/b><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">80280X<\/td><td class=\"column-2\">Walk 5.0<\/td><td class=\"column-3\"><b>--<sup>a<\/sup><\/b><\/td><td class=\"column-4\"><b>--<sup>a<\/sup><\/b><\/td><td class=\"column-5\"><b>7.9<\/b><\/td><td class=\"column-6\">8.5<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">80300X<\/td><td class=\"column-2\">Walk Self-Paced Brisk<\/td><td class=\"column-3\"><b>4.6<\/b><\/td><td class=\"column-4\"><b>5.0<\/b><\/td><td class=\"column-5\">5.1<\/td><td class=\"column-6\">5.5<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">80320X<\/td><td class=\"column-2\">Walk Self-Paced Casual<\/td><td class=\"column-3\"><b>3.6<\/b><\/td><td class=\"column-4\"><b>3.9<\/b><\/td><td class=\"column-5\"><b>4.3<\/b><\/td><td class=\"column-6\">4.5<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-22 from cache -->\n<\/div>\n<\/div>\n<div class=\"wpcmsdev-toggle\">\n<h3 class=\"toggle-title\"><a href=\"#toggle-weight-lifting\"><i class=\"fa fa-plus icon-for-inactive\"><\/i><i class=\"fa fa-minus icon-for-active\"><\/i>Weight Lifting*<\/a><\/h3>\n<div id=\"toggle-weight-lifting\" class=\"toggle-content\">\n\n<table id=\"tablepress-23\" class=\"tablepress tablepress-id-23 mety\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MET<sub>y<\/sub> Code<\/th><th class=\"column-2\">Specific Activity<\/th><th class=\"column-3\">Ages <br>6-9<\/th><th class=\"column-4\">Ages <br>10-12<\/th><th class=\"column-5\">Ages <br>13-15<\/th><th class=\"column-6\">Ages <br>16-18<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">85100X<\/td><td class=\"column-2\">Hand Weights Exercises<\/td><td class=\"column-3\"><b>3.0<\/b><\/td><td class=\"column-4\"><b>3.3<\/b><\/td><td class=\"column-5\">3.2<\/td><td class=\"column-6\">3.2<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">85120X<\/td><td class=\"column-2\">Strength Exercises - Bench Press<\/td><td class=\"column-3\"><b>1.7<\/b><\/td><td class=\"column-4\"><b>1.9<\/b><\/td><td class=\"column-5\"><b>1.9<\/b><\/td><td class=\"column-6\"><b>1.8<\/b><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">85140X<\/td><td class=\"column-2\">Strength Exercises - Leg Press<\/td><td class=\"column-3\"><b>2.2<\/b><\/td><td class=\"column-4\"><b>2.7<\/b><\/td><td class=\"column-5\"><b>3.2<\/b><\/td><td class=\"column-6\"><b>3.2<\/b><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-23 from cache -->\n<\/div>\n<\/div>\n<p><strong>Bolded<\/strong> METy values are observed values from the literature.<br \/>\nAge group is designated by the placeholder X; the age ranges are represented by 2 (6-9 y), 3 (10-12 y), 4 (13-15 y), and 5 (16-18 y).<br \/>\n<sup>a<\/sup> Activity not deemed reasonable for this age group<br \/>\n*Energy cost of anaerobic activities may be underestimated by MET values.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bolded METy values are observed values from the literature. Age group is designated by the placeholder X; the age ranges are represented by 2 (6-9 y), 3 (10-12 y), 4 (13-15 y), and 5 (16-18 y). a Activity not deemed reasonable for this age group *Energy cost of anaerobic activities may be underestimated by MET [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-81","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Bolded METy values are observed values from the literature. Age group is designated by the placeholder X; the age ranges are represented by 2 (6-9 y), 3 (10-12 y), 4 (13-15 y), and 5 (16-18 y). a Activity not deemed reasonable for this age group *Energy cost of anaerobic activities may be underestimated by MET\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.nccor.org\/tools-youthcompendium\/view-by-individual-category\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"NCCOR Youth Compendium of Physical Activities - Youth Compendium Tool\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"METy Values (Observed\/Imputed) \u2013 View by Individual Category - NCCOR Youth Compendium of Physical Activities\" \/>\n\t\t<meta property=\"og:description\" content=\"Bolded METy values are observed values from the literature. Age group is designated by the placeholder X; the age ranges are represented by 2 (6-9 y), 3 (10-12 y), 4 (13-15 y), and 5 (16-18 y). a Activity not deemed reasonable for this age group *Energy cost of anaerobic activities may be underestimated by MET\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.nccor.org\/tools-youthcompendium\/view-by-individual-category\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-03-22T19:17:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-10-18T13:23:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"METy Values (Observed\/Imputed) \u2013 View by Individual Category - NCCOR Youth Compendium of Physical Activities\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Bolded METy values are observed values from the literature. Age group is designated by the placeholder X; the age ranges are represented by 2 (6-9 y), 3 (10-12 y), 4 (13-15 y), and 5 (16-18 y). a Activity not deemed reasonable for this age group *Energy cost of anaerobic activities may be underestimated by MET\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\\\/view-by-individual-category\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\\\/view-by-individual-category\\\/#listItem\",\"name\":\"METy Values (Observed\\\/Imputed) \\u2013 View by Individual Category\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\\\/view-by-individual-category\\\/#listItem\",\"position\":2,\"name\":\"METy Values (Observed\\\/Imputed) \\u2013 View by Individual Category\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\\\/#organization\",\"name\":\"NCCOR Youth Compendium of Physical Activities\",\"description\":\"Youth Compendium Tool\",\"url\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\\\/view-by-individual-category\\\/#webpage\",\"url\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\\\/view-by-individual-category\\\/\",\"name\":\"METy Values (Observed\\\/Imputed) \\u2013 View by Individual Category - NCCOR Youth Compendium of Physical Activities\",\"description\":\"Bolded METy values are observed values from the literature. Age group is designated by the placeholder X; the age ranges are represented by 2 (6-9 y), 3 (10-12 y), 4 (13-15 y), and 5 (16-18 y). a Activity not deemed reasonable for this age group *Energy cost of anaerobic activities may be underestimated by MET\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\\\/view-by-individual-category\\\/#breadcrumblist\"},\"datePublished\":\"2017-03-22T19:17:25+00:00\",\"dateModified\":\"2017-10-18T13:23:16+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\\\/#website\",\"url\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\\\/\",\"name\":\"NCCOR Youth Compendium of Physical Activities\",\"description\":\"Youth Compendium Tool\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nccor.org\\\/tools-youthcompendium\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"METy Values (Observed\/Imputed) \u2013 View by Individual Category - NCCOR Youth Compendium of Physical Activities","description":"Bolded METy values are observed values from the literature. Age group is designated by the placeholder X; the age ranges are represented by 2 (6-9 y), 3 (10-12 y), 4 (13-15 y), and 5 (16-18 y). a Activity not deemed reasonable for this age group *Energy cost of anaerobic activities may be underestimated by MET","canonical_url":"https:\/\/www.nccor.org\/tools-youthcompendium\/view-by-individual-category\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.nccor.org\/tools-youthcompendium\/view-by-individual-category\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.nccor.org\/tools-youthcompendium#listItem","position":1,"name":"Home","item":"https:\/\/www.nccor.org\/tools-youthcompendium","nextItem":{"@type":"ListItem","@id":"https:\/\/www.nccor.org\/tools-youthcompendium\/view-by-individual-category\/#listItem","name":"METy Values (Observed\/Imputed) \u2013 View by Individual Category"}},{"@type":"ListItem","@id":"https:\/\/www.nccor.org\/tools-youthcompendium\/view-by-individual-category\/#listItem","position":2,"name":"METy Values (Observed\/Imputed) \u2013 View by Individual Category","previousItem":{"@type":"ListItem","@id":"https:\/\/www.nccor.org\/tools-youthcompendium#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/www.nccor.org\/tools-youthcompendium\/#organization","name":"NCCOR Youth Compendium of Physical Activities","description":"Youth Compendium Tool","url":"https:\/\/www.nccor.org\/tools-youthcompendium\/"},{"@type":"WebPage","@id":"https:\/\/www.nccor.org\/tools-youthcompendium\/view-by-individual-category\/#webpage","url":"https:\/\/www.nccor.org\/tools-youthcompendium\/view-by-individual-category\/","name":"METy Values (Observed\/Imputed) \u2013 View by Individual Category - NCCOR Youth Compendium of Physical Activities","description":"Bolded METy values are observed values from the literature. Age group is designated by the placeholder X; the age ranges are represented by 2 (6-9 y), 3 (10-12 y), 4 (13-15 y), and 5 (16-18 y). a Activity not deemed reasonable for this age group *Energy cost of anaerobic activities may be underestimated by MET","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.nccor.org\/tools-youthcompendium\/#website"},"breadcrumb":{"@id":"https:\/\/www.nccor.org\/tools-youthcompendium\/view-by-individual-category\/#breadcrumblist"},"datePublished":"2017-03-22T19:17:25+00:00","dateModified":"2017-10-18T13:23:16+00:00"},{"@type":"WebSite","@id":"https:\/\/www.nccor.org\/tools-youthcompendium\/#website","url":"https:\/\/www.nccor.org\/tools-youthcompendium\/","name":"NCCOR Youth Compendium of Physical Activities","description":"Youth Compendium Tool","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.nccor.org\/tools-youthcompendium\/#organization"}}]},"og:locale":"en_US","og:site_name":"NCCOR Youth Compendium of Physical Activities - Youth Compendium Tool","og:type":"article","og:title":"METy Values (Observed\/Imputed) \u2013 View by Individual Category - NCCOR Youth Compendium of Physical Activities","og:description":"Bolded METy values are observed values from the literature. Age group is designated by the placeholder X; the age ranges are represented by 2 (6-9 y), 3 (10-12 y), 4 (13-15 y), and 5 (16-18 y). a Activity not deemed reasonable for this age group *Energy cost of anaerobic activities may be underestimated by MET","og:url":"https:\/\/www.nccor.org\/tools-youthcompendium\/view-by-individual-category\/","article:published_time":"2017-03-22T19:17:25+00:00","article:modified_time":"2017-10-18T13:23:16+00:00","twitter:card":"summary_large_image","twitter:title":"METy Values (Observed\/Imputed) \u2013 View by Individual Category - NCCOR Youth Compendium of Physical Activities","twitter:description":"Bolded METy values are observed values from the literature. Age group is designated by the placeholder X; the age ranges are represented by 2 (6-9 y), 3 (10-12 y), 4 (13-15 y), and 5 (16-18 y). a Activity not deemed reasonable for this age group *Energy cost of anaerobic activities may be underestimated by MET"},"aioseo_meta_data":{"post_id":"81","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-18 22:30:52","updated":"2025-11-07 02:29:21","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.nccor.org\/tools-youthcompendium\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMET<sub>y<\/sub> Values (Observed\/Imputed) \u2013 View by Individual Category\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.nccor.org\/tools-youthcompendium"},{"label":"MET<sub>y<\/sub> Values (Observed\/Imputed) \u2013 View by Individual Category","link":"https:\/\/www.nccor.org\/tools-youthcompendium\/view-by-individual-category\/"}],"_links":{"self":[{"href":"https:\/\/www.nccor.org\/tools-youthcompendium\/wp-json\/wp\/v2\/pages\/81","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nccor.org\/tools-youthcompendium\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nccor.org\/tools-youthcompendium\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nccor.org\/tools-youthcompendium\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nccor.org\/tools-youthcompendium\/wp-json\/wp\/v2\/comments?post=81"}],"version-history":[{"count":0,"href":"https:\/\/www.nccor.org\/tools-youthcompendium\/wp-json\/wp\/v2\/pages\/81\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.nccor.org\/tools-youthcompendium\/wp-json\/wp\/v2\/media?parent=81"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}